{"id":247,"date":"2021-04-29T03:36:59","date_gmt":"2021-04-29T03:36:59","guid":{"rendered":"https:\/\/elastomer-technik.com\/contact"},"modified":"2023-03-27T06:59:26","modified_gmt":"2023-03-27T06:59:26","slug":"contact","status":"publish","type":"page","link":"https:\/\/elastomer-technik.com\/de\/contact","title":{"rendered":"KONTAKT"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"247\" class=\"elementor elementor-247\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-679c340 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"679c340\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c7c7c2\" data-id=\"6c7c7c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c859a3 elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"6c859a3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h1 class=\"elementor-image-box-title\">Kontaktieren Sie Uns<\/h1><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98ea6fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98ea6fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c201174\" data-id=\"c201174\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27cc415 elementor-widget elementor-widget-spacer\" data-id=\"27cc415\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a4b8ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a4b8ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5ac269\" data-id=\"e5ac269\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ef8430 elementor-widget elementor-widget-wpforms\" data-id=\"1ef8430\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container\" id=\"wpforms-1163\"><form id=\"wpforms-form-1163\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1163\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/247\" data-token=\"b4df391a6cd22749c9640c68f4477347\" data-token-time=\"1778678309\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/247\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1163-field_5-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-1163-field_5\">Unternehmen<\/label><input type=\"text\" id=\"wpforms-1163-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" ><\/div><div id=\"wpforms-1163-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-1163-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-1163-field_0\" class=\"wpforms-field-sublabel after\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-1163-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-1163-field_0-last\" class=\"wpforms-field-sublabel after\">Nachname<\/label><\/div><\/div><\/div><div id=\"wpforms-1163-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-1163-field_1\">E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1163-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1163-field_9-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-1163-field_9\">Phone number<\/label><input type=\"text\" id=\"wpforms-1163-field_9\" class=\"wpforms-field-medium\" name=\"wpforms[fields][9]\" ><\/div><div id=\"wpforms-1163-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-1163-field_6\">Betreff<\/label><input type=\"text\" id=\"wpforms-1163-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" ><\/div><div id=\"wpforms-1163-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-1163-field_2\">Nachricht<\/label><textarea id=\"wpforms-1163-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-hcaptcha\" ><div class=\"h-captcha\" data-sitekey=\"78f0aae3-c400-4e40-b79e-4913bde67ce5\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-hcaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1163\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/pages\/247\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1163\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Nachricht Senden<\/button><img decoding=\"async\" src=\"https:\/\/elastomer-technik.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Kontaktieren Sie Uns<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-247","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/pages\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":14,"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/pages\/247\/revisions"}],"predecessor-version":[{"id":1243,"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/pages\/247\/revisions\/1243"}],"wp:attachment":[{"href":"https:\/\/elastomer-technik.com\/de\/wp-json\/wp\/v2\/media?parent=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}